{"id":1377,"date":"2020-02-02T17:43:18","date_gmt":"2020-02-02T16:43:18","guid":{"rendered":"https:\/\/www.cotesducouchois.com\/?p=1377"},"modified":"2020-03-02T17:40:35","modified_gmt":"2020-03-02T16:40:35","slug":"2020-02-le-depeche","status":"publish","type":"post","link":"https:\/\/www.cotesducouchois.com\/en\/newsletter\/2020-02-le-depeche\/","title":{"rendered":"La d\u00e9p\u00eache &#8211; F\u00e9vrier 2020"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Pour ne pas dire infernaux tant la t\u00e2che est lourde tout autant que la terre est dure. La vigne et ses saisons bercent le rythme du temps en d\u00e9butant par la pr\u00e9paration du sol et de l\u2019arbre puis viendront la pousse et l\u2019entretien, le m\u00fbrissement avant les vendanges et enfin la vinification puis l\u2019\u00e9levage avant que ne reprenne ce cycle ancestral qui anime la Bourgogne depuis bient\u00f4t deux mille ans.<\/p>","protected":false},"author":1,"featured_media":1378,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[38],"tags":[],"class_list":["post-1377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsletter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La d\u00e9p\u00eache - F\u00e9vrier 2020 - C\u00f4tes du Couchois<\/title>\n<meta name=\"description\" content=\"Pour ne pas dire infernaux tant la t\u00e2che est lourde, et la terre est dure. La vigne et ses saisons bercent le rythme en d\u00e9butant par la pr\u00e9paration du sol\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cotesducouchois.com\/en\/newsletter\/2020-02-le-depeche\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La d\u00e9p\u00eache - F\u00e9vrier 2020 - C\u00f4tes du Couchois\" \/>\n<meta property=\"og:description\" content=\"Pour ne pas dire infernaux tant la t\u00e2che est lourde, et la terre est dure. La vigne et ses saisons bercent le rythme en d\u00e9butant par la pr\u00e9paration du sol\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cotesducouchois.com\/en\/newsletter\/2020-02-le-depeche\/\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4tes du Couchois\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-02T16:43:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-02T16:40:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cotesducouchois.com\/wp-content\/uploads\/2020\/02\/La-Depeche-Fevrier-2020.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"249\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maestro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maestro\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2020-02-le-depeche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2020-02-le-depeche\\\/\"},\"author\":{\"name\":\"Maestro\",\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/#\\\/schema\\\/person\\\/afd65c9fa0c78ebc70be04e108e15de0\"},\"headline\":\"La d\u00e9p\u00eache &#8211; F\u00e9vrier 2020\",\"datePublished\":\"2020-02-02T16:43:18+00:00\",\"dateModified\":\"2020-03-02T16:40:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2020-02-le-depeche\\\/\"},\"wordCount\":7,\"image\":{\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2020-02-le-depeche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cotesducouchois.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/La-Depeche-Fevrier-2020.jpg\",\"articleSection\":[\"La d\u00e9p\u00eache de l'union\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2020-02-le-depeche\\\/\",\"url\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2020-02-le-depeche\\\/\",\"name\":\"La d\u00e9p\u00eache - F\u00e9vrier 2020 - C\u00f4tes du Couchois\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2020-02-le-depeche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2020-02-le-depeche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cotesducouchois.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/La-Depeche-Fevrier-2020.jpg\",\"datePublished\":\"2020-02-02T16:43:18+00:00\",\"dateModified\":\"2020-03-02T16:40:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/#\\\/schema\\\/person\\\/afd65c9fa0c78ebc70be04e108e15de0\"},\"description\":\"Pour ne pas dire infernaux tant la t\u00e2che est lourde, et la terre est dure. La vigne et ses saisons bercent le rythme en d\u00e9butant par la pr\u00e9paration du sol\u2026\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2020-02-le-depeche\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2020-02-le-depeche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2020-02-le-depeche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cotesducouchois.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/La-Depeche-Fevrier-2020.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cotesducouchois.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/La-Depeche-Fevrier-2020.jpg\",\"width\":400,\"height\":249,\"caption\":\"les vignes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2020-02-le-depeche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.cotesducouchois.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La d\u00e9p\u00eache &#8211; F\u00e9vrier 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cotesducouchois.com\\\/\",\"name\":\"C\u00f4tes du Couchois\",\"description\":\"Union des producteurs et n\u00e9gociants de l&#039;AOC C\u00f4tes du Couchois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cotesducouchois.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/#\\\/schema\\\/person\\\/afd65c9fa0c78ebc70be04e108e15de0\",\"name\":\"Maestro\",\"url\":\"https:\\\/\\\/www.cotesducouchois.com\\\/en\\\/author\\\/maestro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La d\u00e9p\u00eache - F\u00e9vrier 2020 - C\u00f4tes du Couchois","description":"Pour ne pas dire infernaux tant la t\u00e2che est lourde, et la terre est dure. La vigne et ses saisons bercent le rythme en d\u00e9butant par la pr\u00e9paration du sol\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cotesducouchois.com\/en\/newsletter\/2020-02-le-depeche\/","og_locale":"en_GB","og_type":"article","og_title":"La d\u00e9p\u00eache - F\u00e9vrier 2020 - C\u00f4tes du Couchois","og_description":"Pour ne pas dire infernaux tant la t\u00e2che est lourde, et la terre est dure. La vigne et ses saisons bercent le rythme en d\u00e9butant par la pr\u00e9paration du sol\u2026","og_url":"https:\/\/www.cotesducouchois.com\/en\/newsletter\/2020-02-le-depeche\/","og_site_name":"C\u00f4tes du Couchois","article_published_time":"2020-02-02T16:43:18+00:00","article_modified_time":"2020-03-02T16:40:35+00:00","og_image":[{"width":400,"height":249,"url":"https:\/\/www.cotesducouchois.com\/wp-content\/uploads\/2020\/02\/La-Depeche-Fevrier-2020.jpg","type":"image\/jpeg"}],"author":"Maestro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Maestro"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2020-02-le-depeche\/#article","isPartOf":{"@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2020-02-le-depeche\/"},"author":{"name":"Maestro","@id":"https:\/\/www.cotesducouchois.com\/#\/schema\/person\/afd65c9fa0c78ebc70be04e108e15de0"},"headline":"La d\u00e9p\u00eache &#8211; F\u00e9vrier 2020","datePublished":"2020-02-02T16:43:18+00:00","dateModified":"2020-03-02T16:40:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2020-02-le-depeche\/"},"wordCount":7,"image":{"@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2020-02-le-depeche\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cotesducouchois.com\/wp-content\/uploads\/2020\/02\/La-Depeche-Fevrier-2020.jpg","articleSection":["La d\u00e9p\u00eache de l'union"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2020-02-le-depeche\/","url":"https:\/\/www.cotesducouchois.com\/newsletter\/2020-02-le-depeche\/","name":"La d\u00e9p\u00eache - F\u00e9vrier 2020 - C\u00f4tes du Couchois","isPartOf":{"@id":"https:\/\/www.cotesducouchois.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2020-02-le-depeche\/#primaryimage"},"image":{"@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2020-02-le-depeche\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cotesducouchois.com\/wp-content\/uploads\/2020\/02\/La-Depeche-Fevrier-2020.jpg","datePublished":"2020-02-02T16:43:18+00:00","dateModified":"2020-03-02T16:40:35+00:00","author":{"@id":"https:\/\/www.cotesducouchois.com\/#\/schema\/person\/afd65c9fa0c78ebc70be04e108e15de0"},"description":"Pour ne pas dire infernaux tant la t\u00e2che est lourde, et la terre est dure. La vigne et ses saisons bercent le rythme en d\u00e9butant par la pr\u00e9paration du sol\u2026","breadcrumb":{"@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2020-02-le-depeche\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cotesducouchois.com\/newsletter\/2020-02-le-depeche\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2020-02-le-depeche\/#primaryimage","url":"https:\/\/www.cotesducouchois.com\/wp-content\/uploads\/2020\/02\/La-Depeche-Fevrier-2020.jpg","contentUrl":"https:\/\/www.cotesducouchois.com\/wp-content\/uploads\/2020\/02\/La-Depeche-Fevrier-2020.jpg","width":400,"height":249,"caption":"les vignes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2020-02-le-depeche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cotesducouchois.com\/"},{"@type":"ListItem","position":2,"name":"La d\u00e9p\u00eache &#8211; F\u00e9vrier 2020"}]},{"@type":"WebSite","@id":"https:\/\/www.cotesducouchois.com\/#website","url":"https:\/\/www.cotesducouchois.com\/","name":"C\u00f4tes du Couchois","description":"Union des producteurs et n\u00e9gociants de l&#039;AOC C\u00f4tes du Couchois","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cotesducouchois.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.cotesducouchois.com\/#\/schema\/person\/afd65c9fa0c78ebc70be04e108e15de0","name":"Maestro","url":"https:\/\/www.cotesducouchois.com\/en\/author\/maestro\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/posts\/1377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/comments?post=1377"}],"version-history":[{"count":1,"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/posts\/1377\/revisions"}],"predecessor-version":[{"id":1379,"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/posts\/1377\/revisions\/1379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/media\/1378"}],"wp:attachment":[{"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/media?parent=1377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/categories?post=1377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/tags?post=1377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}