{"id":1343,"date":"2019-10-11T09:45:16","date_gmt":"2019-10-11T07:45:16","guid":{"rendered":"https:\/\/www.cotesducouchois.com\/?p=1343"},"modified":"2019-10-11T09:48:25","modified_gmt":"2019-10-11T07:48:25","slug":"2019-10-la-depeche","status":"publish","type":"post","link":"https:\/\/www.cotesducouchois.com\/en\/newsletter\/2019-10-la-depeche\/","title":{"rendered":"La D\u00e9p\u00eache &#8211; Octobre 2019"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>La D\u00e9p\u00eache du mois dernier en faisait \u00e9tat, les choses n\u2019avaient pas l\u2019air de s\u2019annoncer si mauvaises niveau rendement ; L\u2019entonnage des blancs en cours et les rouges en fin de mac\u00e9ration, l\u2019heure des comptes peut sonner et elle confirme les pressentiments. Si quelques parcelles tr\u00e8s drainantes font bien triste figure avec des rendements n\u2019atteignant pas les 15Hl \u00e0 l\u2019hectare comme c\u2019est le cas dans les crans (sable de granit) ou les gr\u00e8s dans une moindre mesure&#8230;<\/p>","protected":false},"author":1,"featured_media":1345,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[38],"tags":[],"class_list":["post-1343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsletter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La D\u00e9p\u00eache - Octobre 2019 - C\u00f4tes du Couchois<\/title>\n<meta name=\"description\" content=\"L\u2019entonnage des blancs en cours et les rouges en fin de mac\u00e9ration, l\u2019heure des comptes peut sonner et elle confirme les pressentiments\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cotesducouchois.com\/en\/newsletter\/2019-10-la-depeche\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La D\u00e9p\u00eache - Octobre 2019 - C\u00f4tes du Couchois\" \/>\n<meta property=\"og:description\" content=\"L\u2019entonnage des blancs en cours et les rouges en fin de mac\u00e9ration, l\u2019heure des comptes peut sonner et elle confirme les pressentiments\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cotesducouchois.com\/en\/newsletter\/2019-10-la-depeche\/\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4tes du Couchois\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-11T07:45:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-11T07:48:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cotesducouchois.com\/wp-content\/uploads\/2019\/10\/2019-10-la-depeche.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maestro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maestro\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2019-10-la-depeche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2019-10-la-depeche\\\/\"},\"author\":{\"name\":\"Maestro\",\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/#\\\/schema\\\/person\\\/afd65c9fa0c78ebc70be04e108e15de0\"},\"headline\":\"La D\u00e9p\u00eache &#8211; Octobre 2019\",\"datePublished\":\"2019-10-11T07:45:16+00:00\",\"dateModified\":\"2019-10-11T07:48:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2019-10-la-depeche\\\/\"},\"wordCount\":6,\"image\":{\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2019-10-la-depeche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cotesducouchois.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/2019-10-la-depeche.jpg\",\"articleSection\":[\"La d\u00e9p\u00eache de l'union\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2019-10-la-depeche\\\/\",\"url\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2019-10-la-depeche\\\/\",\"name\":\"La D\u00e9p\u00eache - Octobre 2019 - C\u00f4tes du Couchois\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2019-10-la-depeche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2019-10-la-depeche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cotesducouchois.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/2019-10-la-depeche.jpg\",\"datePublished\":\"2019-10-11T07:45:16+00:00\",\"dateModified\":\"2019-10-11T07:48:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/#\\\/schema\\\/person\\\/afd65c9fa0c78ebc70be04e108e15de0\"},\"description\":\"L\u2019entonnage des blancs en cours et les rouges en fin de mac\u00e9ration, l\u2019heure des comptes peut sonner et elle confirme les pressentiments\u2026\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2019-10-la-depeche\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2019-10-la-depeche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2019-10-la-depeche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cotesducouchois.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/2019-10-la-depeche.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cotesducouchois.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/2019-10-la-depeche.jpg\",\"width\":400,\"height\":250,\"caption\":\"mac\u00e9ration du vin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/newsletter\\\/2019-10-la-depeche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.cotesducouchois.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La D\u00e9p\u00eache &#8211; Octobre 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cotesducouchois.com\\\/\",\"name\":\"C\u00f4tes du Couchois\",\"description\":\"Union des producteurs et n\u00e9gociants de l&#039;AOC C\u00f4tes du Couchois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cotesducouchois.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cotesducouchois.com\\\/#\\\/schema\\\/person\\\/afd65c9fa0c78ebc70be04e108e15de0\",\"name\":\"Maestro\",\"url\":\"https:\\\/\\\/www.cotesducouchois.com\\\/en\\\/author\\\/maestro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La D\u00e9p\u00eache - Octobre 2019 - C\u00f4tes du Couchois","description":"L\u2019entonnage des blancs en cours et les rouges en fin de mac\u00e9ration, l\u2019heure des comptes peut sonner et elle confirme les pressentiments\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cotesducouchois.com\/en\/newsletter\/2019-10-la-depeche\/","og_locale":"en_GB","og_type":"article","og_title":"La D\u00e9p\u00eache - Octobre 2019 - C\u00f4tes du Couchois","og_description":"L\u2019entonnage des blancs en cours et les rouges en fin de mac\u00e9ration, l\u2019heure des comptes peut sonner et elle confirme les pressentiments\u2026","og_url":"https:\/\/www.cotesducouchois.com\/en\/newsletter\/2019-10-la-depeche\/","og_site_name":"C\u00f4tes du Couchois","article_published_time":"2019-10-11T07:45:16+00:00","article_modified_time":"2019-10-11T07:48:25+00:00","og_image":[{"width":400,"height":250,"url":"https:\/\/www.cotesducouchois.com\/wp-content\/uploads\/2019\/10\/2019-10-la-depeche.jpg","type":"image\/jpeg"}],"author":"Maestro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Maestro"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2019-10-la-depeche\/#article","isPartOf":{"@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2019-10-la-depeche\/"},"author":{"name":"Maestro","@id":"https:\/\/www.cotesducouchois.com\/#\/schema\/person\/afd65c9fa0c78ebc70be04e108e15de0"},"headline":"La D\u00e9p\u00eache &#8211; Octobre 2019","datePublished":"2019-10-11T07:45:16+00:00","dateModified":"2019-10-11T07:48:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2019-10-la-depeche\/"},"wordCount":6,"image":{"@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2019-10-la-depeche\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cotesducouchois.com\/wp-content\/uploads\/2019\/10\/2019-10-la-depeche.jpg","articleSection":["La d\u00e9p\u00eache de l'union"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2019-10-la-depeche\/","url":"https:\/\/www.cotesducouchois.com\/newsletter\/2019-10-la-depeche\/","name":"La D\u00e9p\u00eache - Octobre 2019 - C\u00f4tes du Couchois","isPartOf":{"@id":"https:\/\/www.cotesducouchois.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2019-10-la-depeche\/#primaryimage"},"image":{"@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2019-10-la-depeche\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cotesducouchois.com\/wp-content\/uploads\/2019\/10\/2019-10-la-depeche.jpg","datePublished":"2019-10-11T07:45:16+00:00","dateModified":"2019-10-11T07:48:25+00:00","author":{"@id":"https:\/\/www.cotesducouchois.com\/#\/schema\/person\/afd65c9fa0c78ebc70be04e108e15de0"},"description":"L\u2019entonnage des blancs en cours et les rouges en fin de mac\u00e9ration, l\u2019heure des comptes peut sonner et elle confirme les pressentiments\u2026","breadcrumb":{"@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2019-10-la-depeche\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cotesducouchois.com\/newsletter\/2019-10-la-depeche\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2019-10-la-depeche\/#primaryimage","url":"https:\/\/www.cotesducouchois.com\/wp-content\/uploads\/2019\/10\/2019-10-la-depeche.jpg","contentUrl":"https:\/\/www.cotesducouchois.com\/wp-content\/uploads\/2019\/10\/2019-10-la-depeche.jpg","width":400,"height":250,"caption":"mac\u00e9ration du vin"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cotesducouchois.com\/newsletter\/2019-10-la-depeche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cotesducouchois.com\/"},{"@type":"ListItem","position":2,"name":"La D\u00e9p\u00eache &#8211; Octobre 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.cotesducouchois.com\/#website","url":"https:\/\/www.cotesducouchois.com\/","name":"C\u00f4tes du Couchois","description":"Union des producteurs et n\u00e9gociants de l&#039;AOC C\u00f4tes du Couchois","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cotesducouchois.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.cotesducouchois.com\/#\/schema\/person\/afd65c9fa0c78ebc70be04e108e15de0","name":"Maestro","url":"https:\/\/www.cotesducouchois.com\/en\/author\/maestro\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/posts\/1343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/comments?post=1343"}],"version-history":[{"count":2,"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/posts\/1343\/revisions"}],"predecessor-version":[{"id":1346,"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/posts\/1343\/revisions\/1346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/media\/1345"}],"wp:attachment":[{"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/media?parent=1343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/categories?post=1343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cotesducouchois.com\/en\/wp-json\/wp\/v2\/tags?post=1343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}